{"id":230,"date":"2015-08-25T10:23:35","date_gmt":"2015-08-25T10:23:35","guid":{"rendered":"https:\/\/www.zotal.com\/inicio\/?lang=en"},"modified":"2026-04-15T12:32:48","modified_gmt":"2026-04-15T10:32:48","slug":"inicio","status":"publish","type":"page","link":"https:\/\/www.zotal.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"230\" class=\"elementor elementor-230 elementor-58\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-1569575a elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"1569575a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23942391 jltma-glass-effect-no\" data-id=\"23942391\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79c94dfb jltma-glass-effect-no elementor-widget elementor-widget-slider_revolution\" data-id=\"79c94dfb\" data-element_type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Inicio navidad REVOLUTION SLIDER 6.6.14 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_76_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:rgba(0,148,170,0);padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_76_1\" style=\"\" data-version=\"6.6.14\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-204\" data-title=\"Inicio 1\" data-anim=\"ms:10;\" data-in=\"o:1;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Inicio 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-204-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:220px,205px,167px,56px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:45,45,38,35;l:37,36,31,30;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-46px,-43px,-38px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>THE EFFICACY <br \/>\nYOU NEED \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-204-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:283px,270px,222px,108px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,18,18;l:25,24,20,20;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,362px,295px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:20;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-50px,-53px,-20px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>> Experts in biosecurity since 1909. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-204-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/en\/gama\/disinfectants\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:730px,600px,443px,0;yo:0,33px,19px,200px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,5;l:0,20,15,7;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:371px,326px,276px,237px;h:552px,485px,410px,352px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:50,41,31,14;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/05\/zotal_z_.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-202\" data-title=\"Inicio 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Inicio 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-202-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:220px,205px,167px,56px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:45,45,38,35;l:37,36,31,30;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-46px,-43px,-38px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>NEW<br \/>\nDISINFECTANT \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-202-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/desinfectantes-industriales\/zotal-zero-lzg\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:283px,270px,222px,108px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,18,18;l:25,24,20,20;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:391px,426px,343px,295px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:20;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-50px,-53px,-20px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>> Effective against African swine fever, PRSS and avian influenza.<br \/>\nDiscover it. \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-202-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/desinfectantes-industriales\/zotal-zero-lzg\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:730px,600px,443px,0;yo:10px,53px,44px,215px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,5;l:0,20,15,7;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:371px,326px,276px,237px;h:552px,485px,410px,352px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:50,41,31,14;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/zotal_LZG.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-203\" data-title=\"Inicio 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Inicio 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-203-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:220px,205px,167px,56px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:45,45,38,35;l:37,36,31,30;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-46px,-43px,-38px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>NEW RANGE: <br \/>\nZOTAL HOME \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-203-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/zotalhogar.com\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:135px,100px,55px,0;yo:283px,270px,222px,108px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,18,18;l:25,24,20,20;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:auto,auto,307px,295px;\"\n\t\t\t\t\t\t\t\tdata-margin=\"t:20;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-50,-50px,-53px,-20px;y:0,0px,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0px,0px,0px;y:0,0px,0px,0px;sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>> Discover it. \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-76-slide-203-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/zotalhogar.com\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:674px,521px,373px,0;yo:22px,33px,19px,200px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,5;l:0,20,15,7;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:451px,435px,354px,290px;h:574px,554px,451px,369px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:50,41,31,14;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"700\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_hogar-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_76_1',rl:[1240,1024,778,480],el:[600,600,500,600],gw:[1240,1024,778,375],gh:[600,600,500,600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider761\"]!==undefined) {window.RS_MODULES.modules[\"revslider761\"].once = false;window.revapi76 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-3e63ae1c elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"3e63ae1c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b372692 jltma-glass-effect-no\" data-id=\"4b372692\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dde47bb jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6dde47bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pioneers in <br>Animal Biosafety<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-408d6f97 jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"408d6f97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Zotal Laboratories <\/strong>has over 100 years of experience\u00a0behind it and is one of Spain\u2019s leaders in biosecurity. It has permits from the Spanish Ministry of Health and Consumer Affairs, the Spanish Agency for Medicines and Healthcare Products (AEMPS), and the Ministry of Agriculture, Fisheries and Food.<\/p><p>It\u2019s a laboratory that\u2019s pioneering the creation of animal health products, is registered as a top-level laboratory with AEMPS and has registered and sold its products in numerous countries in Europe, America, Asia and Africa.<\/p><p>The efficacy of its products is well recognised, and \u201cZotal\u201d has even been included in the Royal Academy of the Spanish Language\u2019s dictionary as a word meaning disinfectant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-5adf553b elementor-section-content-space-between elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"5adf553b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-627ce8e jltma-glass-effect-no elementor-invisible\" data-id=\"627ce8e\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f5defc jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7f5defc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"109\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/formulasunicasicon.svg\" class=\"attachment-full size-full wp-image-9849\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d43008 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"5d43008\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">UNIQUE<br>\nFORMULAS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-618d60a0 jltma-glass-effect-no elementor-invisible\" data-id=\"618d60a0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2da3f61b jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2da3f61b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"89\" height=\"89\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/facilusoicon.svg\" class=\"attachment-full size-full wp-image-9847\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd1efc8 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4fd1efc8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EASY<br>\nTO USE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4618a6a4 jltma-glass-effect-no elementor-invisible\" data-id=\"4618a6a4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32258e06 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"32258e06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"94\" height=\"96\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/eficaciatestadaicon.svg\" class=\"attachment-full size-full wp-image-9845\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd57bd0 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2fd57bd0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TESTED<br>\n EFFICACY<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-61573d5f jltma-glass-effect-no elementor-invisible\" data-id=\"61573d5f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:900}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c268f2d jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"c268f2d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"99\" height=\"99\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/respetoalmedioicon.svg\" class=\"attachment-full size-full wp-image-9852\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a869a8e jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a869a8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">RESPECT FOR<br>\nTHE ENVIRONMENT<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-41ff858a elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"41ff858a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-358b60a0 jltma-glass-effect-no\" data-id=\"358b60a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51922b88 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"51922b88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">New releases<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-2a349ce1 elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"2a349ce1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-343a1a2b jltma-glass-effect-no\" data-id=\"343a1a2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-307574ab jltma-glass-effect-no elementor-widget elementor-widget-slider_revolution\" data-id=\"307574ab\" data-element_type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Slider novedadesINGLES NUEVO REVOLUTION SLIDER 6.6.14 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_75_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_75_2\" style=\"\" data-version=\"6.6.14\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-210\" data-title=\"Novedades 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-210-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,552px,415px,0;yo:155px,164px,104px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:262px,300px,235px,308px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>NOW I ALSO USE IT BY THE GENERAL PUBLIC \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-210-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,552px,415px,0;yo:325px,333px,236px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>Formats in 250 ml and 1 L. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-210-layer-4\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/en\/products\/insecticides\/arpon-diazipol\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:177px,157px,101px,0;y:t,t,m,m;yo:18px,62px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,321px,258px,305px;h:515px,477px,384px,453px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"602\" height=\"858\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2024\/05\/zotal_arpondiazipol.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-210-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,552px,414px,0;y:t,t,m,m;yo:376px,385px,92px,-110px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,162px,130px,170px;h:32px,39px,31px,41px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"414\" height=\"81\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_arpon_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-196\" data-title=\"Novedades 3\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 3\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-196-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:585px,479px,334px,1px;yo:271px,284px,191px,144px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,34,38;l:39,39,33,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:434px,432px,373px,480px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0px,0px;y:0,0,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0px,0px;y:0,0,0px,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>NEW PRESENTATION<br \/>\nSAME EFFECTIVENESS<br \/>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-196-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:584px,479px,332px,-4px;y:t,t,m,m;yo:163px,179px,-62px,-304px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:196px,186px,166px,195px;h:82px,78px,70px,82px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"157\" height=\"65\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/zotal_zero_logo-1.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-196-layer-7\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:586px,482px,333px,0;yo:361px,380px,269px,227px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:326px,307px,302px,406px;h:62px,auto,65px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>Disinfection without contemplations anywhere with a lemon scent. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-196-layer-8\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:301px,209px,137px,-1px;y:t,t,m,m;yo:28px,57px,6px,151px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:192px,178px,132px,155px;h:548px,506px,376px,443px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"301\" height=\"858\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2024\/11\/ZOZAL-ZERO_New.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-190\" data-title=\"Novedades 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-190-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:142px,152px,95px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,300px,235px,308px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>OUR <br \/>\nCERTIFIED ECO-FRIENDLY PRODUCTS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-190-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:312px,321px,227px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>New Line of Eco-friendly<br \/>\nProduction Products. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-190-layer-4\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/detergentes-higienizantes\/previo-basic\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:177px,157px,101px,0;y:t,t,m,m;yo:18px,62px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,321px,258px,305px;h:537px,477px,384px,453px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/zotal_previo_basic_-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-190-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,423px,0;y:t,t,m,m;yo:376px,385px,92px,-95px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,162px,130px,170px;h:39px,39px,31px,41px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"408\" height=\"97\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_previo_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-189\" data-title=\"Novedades 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-189-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:142px,152px,95px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,296px,231px,302px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>OUR <br \/>\nCERTIFIED ECO-FRIENDLY PRODUCTS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-189-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:312px,321px,227px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>New Line of Eco-friendly<br \/>\nProduction Products. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-189-layer-4\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/detergentes-higienizantes\/previodiox\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:179px,152px,101px,0;y:t,t,m,m;yo:58px,89px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,331px,263px,318px;h:427px,392px,311px,376px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"710\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/zotal_previo_diox_new.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-189-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,423px,0;y:t,t,m,m;yo:376px,385px,92px,-95px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,162px,130px,170px;h:39px,39px,31px,41px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"408\" height=\"97\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_previo_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-191\" data-title=\"Novedades 3\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 3\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-191-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:142px,152px,95px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,300px,229px,302px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>OUR <br \/>\nCERTIFIED ECO-FRIENDLY PRODUCTS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-191-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:312px,321px,227px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>New Line of Eco-friendly<br \/>\nProduction Products. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-191-layer-4\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/detergentes-higienizantes\/previo-saludine-copia-3\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:177px,157px,101px,0;y:t,t,m,m;yo:18px,62px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,321px,258px,305px;h:537px,477px,384px,453px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_previo_saludine_-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-191-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,423px,0;y:t,t,m,m;yo:376px,385px,92px,-95px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:162px,162px,130px,170px;h:39px,39px,31px,41px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"408\" height=\"97\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_previo_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-194\" data-title=\"Novedades 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-194-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:142px,152px,95px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,298px,234px,308px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>OUR <br \/>\nCERTIFIED ECO-FRIENDLY PRODUCTS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-194-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:312px,321px,227px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>New Line of Eco-friendly<br \/>\nProduction Products. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-194-layer-4\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.zotal.com\/productos\/desinfectantes-industriales\/sanitas-neozital\/\" target=\"_self\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:177px,157px,101px,0;y:t,t,m,m;yo:18px,62px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,321px,258px,305px;h:537px,477px,384px,453px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/zotal_neotizal_.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-194-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,423px,0;y:t,t,m,m;yo:376px,385px,92px,-90px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:189px,188px,155px,186px;h:43px,43px,36px,43px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"418\" height=\"96\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_sanitas_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-188\" data-title=\"Novedades 1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Novedades 1\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-188-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:142px,152px,95px,32px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:40,40,31,40;l:39,39,30,39;fw:700;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:294px,297px,235px,306px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>OUR <br \/>\nCERTIFIED ECO-FRIENDLY PRODUCTS \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-188-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,424px,0;yo:312px,321px,227px,195px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:16,16,16,20;l:19,19,16,23;fw:500;a:left,left,left,center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:308px,254px,215px,336px;h:62px,51px,56px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Poppins';\"\n\t\t\t\t\t\t\t>New Line of Eco-friendly<br \/>\nProduction Products. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-188-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:177px,157px,101px,0;y:t,t,m,m;yo:18px,62px,0,161px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:361px,321px,258px,305px;h:537px,477px,384px,453px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"600\" height=\"892\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/zotal_neotizal_agro_.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-75-slide-188-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:l,l,l,c;xo:655px,559px,423px,0;y:t,t,m,m;yo:376px,385px,92px,-90px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,16,12,7;l:0,20,15,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:189px,188px,155px,186px;h:43px,43px,36px,43px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.zotal.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"418\" height=\"96\" data-lazyload=\"\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_sanitas_logo.svg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_75_2',rl:[1240,1024,778,480],el:[600,600,400,750],gw:[1240,1024,778,480],gh:[600,600,400,750],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider752\"]!==undefined) {window.RS_MODULES.modules[\"revslider752\"].once = false;window.revapi75 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-7e538b56 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"7e538b56\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10c49327 jltma-glass-effect-no\" data-id=\"10c49327\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-706dae2a jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"706dae2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integrated Quality and Environmental Management\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b7c114a jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"5b7c114a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Laboratories Zotal<\/strong>\u00a0is certified with the UNE EN ISO 9001 norms for its Quality Administration and UNE EN ISO 14001 for its Environmental Administration. Excellence within its administration is a managerial philosophy, while its main challenge is continuous improvement within all departments of the Company: personnel, products, quality, environmental impact and, in the top spot, its clients. Bearing this in mind, and to demonstrate its commitment to the environment, itsEnvironmental Administration system has been validated according to the European Union Regulation (CE) N\u00ba 761\/2001 EMAS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-7389321 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"7389321\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-747b7749 jltma-glass-effect-no\" data-id=\"747b7749\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aa84505 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"1aa84505\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/zotal_calidad_logos.svg\" class=\"attachment-large size-large wp-image-11695\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-6f0bda97 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"6f0bda97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-51f9c584 jltma-glass-effect-no\" data-id=\"51f9c584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f875e jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"74f875e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/05\/iso9001en.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"488\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso9001_logo_blanco.png\" class=\"attachment-large size-large wp-image-12023\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso9001_logo_blanco.png 500w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso9001_logo_blanco-300x293.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso9001_logo_blanco-32x32.png 32w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-435d3722 jltma-glass-effect-no\" data-id=\"435d3722\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30894655 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"30894655\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/05\/iso14001en.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"488\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso14001_logo_blanco.png\" class=\"attachment-large size-large wp-image-12025\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso14001_logo_blanco.png 500w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso14001_logo_blanco-300x293.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/iso14001_logo_blanco-32x32.png 32w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-5e8a10ca jltma-glass-effect-no\" data-id=\"5e8a10ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48348afd jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"48348afd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/emas2023-1.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"507\" height=\"798\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/emas_logo_blanco.png\" class=\"attachment-large size-large wp-image-12019\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/emas_logo_blanco.png 507w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/emas_logo_blanco-191x300.png 191w\" sizes=\"(max-width: 507px) 100vw, 507px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-3ed940b5 jltma-glass-effect-no\" data-id=\"3ed940b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56a43606 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"56a43606\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco.png\" class=\"attachment-large size-large wp-image-12021\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco.png 500w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco-300x300.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco-150x150.png 150w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco-32x32.png 32w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco-400x400.png 400w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/gmp_logo_blanco-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4be32f8b jltma-glass-effect-no\" data-id=\"4be32f8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-332aac84 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"332aac84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2025\/10\/EFR-2024-2026.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"316\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/efr_logo_blanco.png\" class=\"attachment-large size-large wp-image-12017\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/efr_logo_blanco.png 500w, https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/03\/efr_logo_blanco-300x190.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-9da1e78 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"9da1e78\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ab2b40e jltma-glass-effect-no\" data-id=\"6ab2b40e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a468137 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2a468137\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product finder<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8cba jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"4f8cba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At Zotal Laboratories, we have developed a wide range of solutions for various situations and needs. We can assist you in finding the exact product you require. You can download our catalogs or simply let us know your specific needs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-2fdcf103 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"2fdcf103\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-181f607e jltma-glass-effect-no\" data-id=\"181f607e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-3d97e8f2 jltma-glass-effect-no\" data-id=\"3d97e8f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38ddb923 jltma-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"38ddb923\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form data-min-no-for-search=1 data-result-box-max-height=400 data-form-id=9786 class=\"is-search-form is-form-style is-form-style-3 is-form-id-9786 is-ajax-search\" action=\"https:\/\/www.zotal.com\/en\/\" method=\"get\" role=\"search\" ><label for=\"is-search-input-9786\"><span class=\"is-screen-reader-text\">Search for:<\/span><input  type=\"search\" id=\"is-search-input-9786\" name=\"s\" value=\"\" class=\"is-search-input\" placeholder=\"Chinches, detergentes alcalinos\u2026\" autocomplete=off \/><span class=\"is-loader-image\" style=\"display: none;background-image:url(https:\/\/www.zotal.com\/wp-content\/plugins\/add-search-to-menu\/public\/images\/spinner.gif);\" ><\/span><\/label><button type=\"submit\" class=\"is-search-submit\"><span class=\"is-screen-reader-text\">Search Button<\/span><span class=\"is-search-icon\"><svg focusable=\"false\" aria-label=\"Search\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24px\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/span><\/button><input type=\"hidden\" name=\"id\" value=\"9786\" \/><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-58c4109e jltma-glass-effect-no\" data-id=\"58c4109e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-661da9e7 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"661da9e7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-775b2598 jltma-glass-effect-no\" data-id=\"775b2598\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e21e2e7 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2e21e2e7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/AF_Catalogo-ZOTAL-V12_2023_300523_WEB.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok-1024x683.png\" class=\"attachment-large size-large wp-image-9926\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok-1024x683.png 1024w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok-300x200.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok-768x512.png 768w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok-510x340.png 510w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogogeneralok.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-280fd8fc jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"280fd8fc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2021\/06\/catalogozotal2021.pdf\">Professional Catalog\n<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-214aec8d jltma-glass-effect-no\" data-id=\"214aec8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fefdaaa jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"5fefdaaa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2023\/06\/AF_Catalogo-DOMESTICO-ZOTAL_2023_280623_WEB.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-1024x683.png\" class=\"attachment-large size-large wp-image-9929\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-1024x683.png 1024w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-300x200.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-768x512.png 768w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-510x340.png 510w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a791169 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4a791169\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2021\/07\/catalogodomesticozotal2021.pdf\">Home Catalog<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-fb7df74 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"fb7df74\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76aa562 jltma-glass-effect-no\" data-id=\"76aa562\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac4700 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"8ac4700\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions and products finder<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d87e3e jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"0d87e3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At <strong>Zotal Laboratories<\/strong>, we have developed a wide range of solutions for various situations and needs. We can assist you in finding the exact product you require. Enter what you&#8217;re looking for in the following field.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-550113a elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"550113a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5dc5c20 jltma-glass-effect-no\" data-id=\"5dc5c20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-5ee706a jltma-glass-effect-no\" data-id=\"5ee706a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce2209 jltma-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"4ce2209\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form data-min-no-for-search=1 data-result-box-max-height=400 data-form-id=18313 class=\"is-search-form is-form-style is-form-style-3 is-form-id-18313 is-ajax-search\" action=\"https:\/\/www.zotal.com\/en\/\" method=\"get\" role=\"search\" ><label for=\"is-search-input-18313\"><span class=\"is-screen-reader-text\">Search for:<\/span><input  type=\"search\" id=\"is-search-input-18313\" name=\"s\" value=\"\" class=\"is-search-input\" placeholder=\"Bedbugs, alkaline detergents...\" autocomplete=off \/><span class=\"is-loader-image\" style=\"display: none;background-image:url(https:\/\/www.zotal.com\/wp-content\/plugins\/add-search-to-menu\/public\/images\/spinner.gif);\" ><\/span><\/label><button type=\"submit\" class=\"is-search-submit\"><span class=\"is-screen-reader-text\">Search Button<\/span><span class=\"is-search-icon\"><svg focusable=\"false\" aria-label=\"Search\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24px\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/span><\/button><input type=\"hidden\" name=\"id\" value=\"18313\" \/><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a385556 jltma-glass-effect-no\" data-id=\"a385556\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-f40bd7a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"f40bd7a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b73f3a jltma-glass-effect-no\" data-id=\"2b73f3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b1e6d0 elementor-hidden-mobile jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"5b1e6d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Browse our catalogs for more information<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-418b745 elementor-hidden-desktop elementor-hidden-tablet jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"418b745\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Browse our catalogs <br>for more <br>information<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-851bb7e jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"851bb7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Download them and discover all our products.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-2f69a3e elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"2f69a3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10e3738 jltma-glass-effect-no\" data-id=\"10e3738\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-786891d jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"786891d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2025\/11\/AF_Catalogo-ZOTAL-V16_250326_WEB.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026-1024x683.png\" class=\"attachment-large size-large wp-image-23631\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026-1024x683.png 1024w, https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026-300x200.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026-768x512.png 768w, https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026-510x340.png 510w, https:\/\/www.zotal.com\/wp-content\/uploads\/2026\/04\/mockupcatalogogeneralok2026.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aacaca9 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"aacaca9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2025\/11\/AF_Catalogo-ZOTAL-V16_250326_WEB.pdf\">Professional Catalog\n<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17286af jltma-glass-effect-no\" data-id=\"17286af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8796198 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"8796198\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2025\/10\/AF_Catalogo-DOMESTICO-ZOTAL_V10_210725_WEB.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-1024x683.png\" class=\"attachment-large size-large wp-image-9929\" alt=\"\" srcset=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-1024x683.png 1024w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-300x200.png 300w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-768x512.png 768w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook-510x340.png 510w, https:\/\/www.zotal.com\/wp-content\/uploads\/2022\/12\/mockupcatalogodomesticook.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f22860 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6f22860\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2025\/10\/AF_Catalogo-DOMESTICO-ZOTAL_V10_210725_WEB.pdf\">Home Catalog<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-top-section elementor-element elementor-element-557d336 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"557d336\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-243c99ef jltma-glass-effect-no\" data-id=\"243c99ef\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-7d968bb9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default jltma-glass-effect-no\" data-id=\"7d968bb9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-50e65886 jltma-glass-effect-no\" data-id=\"50e65886\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7694fd92 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"7694fd92\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cuidado<br>\nde mascotas<br>\nen oto\u00f1o.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aebe8eb elementor-view-default jltma-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"5aebe8eb\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-798acc1f jltma-glass-effect-no\" data-id=\"798acc1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1ebb85f1 jltma-glass-effect-no\" data-id=\"1ebb85f1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-6f31d93a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default jltma-glass-effect-no\" data-id=\"6f31d93a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e19801 jltma-glass-effect-no\" data-id=\"e19801\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a9267bb jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6a9267bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Consejos de<br>\nlimpieza y<br>\ndesinfecci\u00f3n<br>\nen hosteler\u00eda.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f59b4 elementor-view-default jltma-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"18f59b4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6b1fc8b jltma-glass-effect-no\" data-id=\"6b1fc8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-45fb1229 jltma-glass-effect-no\" data-id=\"45fb1229\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ma_el_bg_slider elementor-section elementor-inner-section elementor-element elementor-element-492890a2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default jltma-glass-effect-no\" data-id=\"492890a2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ma_el_bg_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-15e5d8ca jltma-glass-effect-no\" data-id=\"15e5d8ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743fcf8f jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"743fcf8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como eliminar el Covid en casa.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72e87ff elementor-view-default jltma-glass-effect-no elementor-widget elementor-widget-icon\" data-id=\"72e87ff\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pioneers in Animal Biosafety Zotal Laboratories has over 100 years of experience\u00a0behind it and is one of Spain\u2019s leaders in biosecurity. It has permits from the Spanish Ministry of Health and Consumer Affairs, the Spanish Agency for Medicines and Healthcare Products (AEMPS), and the Ministry of Agriculture, Fisheries and Food. It\u2019s a laboratory that\u2019s pioneering [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7889,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-230","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expertos en bioseguridad | Zotal Laboratorios<\/title>\n<meta name=\"description\" content=\"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zotal.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expertos en bioseguridad | Zotal Laboratorios\" \/>\n<meta property=\"og:description\" content=\"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zotal.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Zotal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zotallaboratorios\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T10:32:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zotallabs\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zotal.com\/en\/\",\"url\":\"https:\/\/www.zotal.com\/en\/\",\"name\":\"Expertos en bioseguridad | Zotal Laboratorios\",\"isPartOf\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg\",\"datePublished\":\"2015-08-25T10:23:35+00:00\",\"dateModified\":\"2026-04-15T10:32:48+00:00\",\"description\":\"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zotal.com\/en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.zotal.com\/en\/#primaryimage\",\"url\":\"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg\",\"contentUrl\":\"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg\",\"width\":720,\"height\":377,\"caption\":\"inicio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zotal.com\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.zotal.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zotal.com\/en\/#website\",\"url\":\"https:\/\/www.zotal.com\/en\/\",\"name\":\"Zotal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zotal.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zotal.com\/en\/#organization\",\"name\":\"Zotal Laboratorios\",\"url\":\"https:\/\/www.zotal.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.zotal.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zotal.com\/wp-content\/uploads\/2015\/08\/zotallogotipo.jpg\",\"contentUrl\":\"https:\/\/www.zotal.com\/wp-content\/uploads\/2015\/08\/zotallogotipo.jpg\",\"width\":706,\"height\":417,\"caption\":\"Zotal Laboratorios\"},\"image\":{\"@id\":\"https:\/\/www.zotal.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/zotallaboratorios\",\"https:\/\/x.com\/zotallabs\",\"https:\/\/es.linkedin.com\/company\/laboratorios-zotal\",\"https:\/\/es.pinterest.com\/zotallabs\/\",\"https:\/\/www.youtube.com\/channel\/UCrNub93hYlNNSerE8khX8JQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expertos en bioseguridad | Zotal Laboratorios","description":"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zotal.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Expertos en bioseguridad | Zotal Laboratorios","og_description":"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.","og_url":"https:\/\/www.zotal.com\/en\/","og_site_name":"Zotal","article_publisher":"https:\/\/www.facebook.com\/zotallaboratorios","article_modified_time":"2026-04-15T10:32:48+00:00","og_image":[{"width":720,"height":377,"url":"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@zotallabs","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zotal.com\/en\/","url":"https:\/\/www.zotal.com\/en\/","name":"Expertos en bioseguridad | Zotal Laboratorios","isPartOf":{"@id":"https:\/\/www.zotal.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zotal.com\/en\/#primaryimage"},"image":{"@id":"https:\/\/www.zotal.com\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg","datePublished":"2015-08-25T10:23:35+00:00","dateModified":"2026-04-15T10:32:48+00:00","description":"Fabricantes de desinfectantes, detergentes, insecticidas, productos para higiene, cuidado y manejo de animales no humanos.","breadcrumb":{"@id":"https:\/\/www.zotal.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zotal.com\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zotal.com\/en\/#primaryimage","url":"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg","contentUrl":"https:\/\/www.zotal.com\/wp-content\/uploads\/2019\/10\/zotalimagendestacadapginainicio.jpg","width":720,"height":377,"caption":"inicio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zotal.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.zotal.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.zotal.com\/en\/#website","url":"https:\/\/www.zotal.com\/en\/","name":"Zotal","description":"","publisher":{"@id":"https:\/\/www.zotal.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zotal.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zotal.com\/en\/#organization","name":"Zotal Laboratorios","url":"https:\/\/www.zotal.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zotal.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.zotal.com\/wp-content\/uploads\/2015\/08\/zotallogotipo.jpg","contentUrl":"https:\/\/www.zotal.com\/wp-content\/uploads\/2015\/08\/zotallogotipo.jpg","width":706,"height":417,"caption":"Zotal Laboratorios"},"image":{"@id":"https:\/\/www.zotal.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zotallaboratorios","https:\/\/x.com\/zotallabs","https:\/\/es.linkedin.com\/company\/laboratorios-zotal","https:\/\/es.pinterest.com\/zotallabs\/","https:\/\/www.youtube.com\/channel\/UCrNub93hYlNNSerE8khX8JQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/pages\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/comments?post=230"}],"version-history":[{"count":205,"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/pages\/230\/revisions"}],"predecessor-version":[{"id":23637,"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/pages\/230\/revisions\/23637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/media\/7889"}],"wp:attachment":[{"href":"https:\/\/www.zotal.com\/en\/wp-json\/wp\/v2\/media?parent=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}